{"id":3573,"date":"2016-02-21T11:29:28","date_gmt":"2016-02-21T10:29:28","guid":{"rendered":"https:\/\/www.starremedies.com\/?page_id=3573"},"modified":"2025-02-05T10:31:03","modified_gmt":"2025-02-05T09:31:03","slug":"madeleine","status":"publish","type":"page","link":"https:\/\/www.starremedies.com\/fr\/madeleine\/","title":{"rendered":"La th\u00e9rapie par les fleurs de Bach par Madeleine Meuwessen"},"content":{"rendered":"<section class=\"section section_breadcrumbs\" id=\"section_1614374484\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row breadcrumbs-row\"  id=\"row-629201198\">\n\n\t<div id=\"col-1112156233\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1850248547\" class=\"text breadcrumbs\">\n\t\t\n<span><span><a href=\"https:\/\/www.starremedies.com\/fr\/\">Accueil<\/a><\/span><\/span>\n\t\t\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-629201198 > .col > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1614374484 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  margin-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section products_row\" id=\"section_489726682\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-middle align-center\"  id=\"row-1417607661\">\n\n\t<div id=\"col-1776100528\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_546257658\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.starremedies.com\/wp-content\/uploads\/2016\/02\/madeleine.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/www.starremedies.com\/wp-content\/uploads\/2016\/02\/madeleine.jpg 300w, https:\/\/www.starremedies.com\/wp-content\/uploads\/2016\/02\/madeleine-80x80.jpg 80w, https:\/\/www.starremedies.com\/wp-content\/uploads\/2016\/02\/madeleine-36x36.jpg 36w, https:\/\/www.starremedies.com\/wp-content\/uploads\/2016\/02\/madeleine-180x180.jpg 180w, https:\/\/www.starremedies.com\/wp-content\/uploads\/2016\/02\/madeleine-120x120.jpg 120w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_546257658 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-877499137\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2585746785\" class=\"text\">\n\t\t\n<h1>BACH TH\u00c9RAPIE FLORALE PAR MADELEINE MEUWESSEN<\/h1>\n\t\t\n<style>\n#text-2585746785 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_489726682 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(247, 247, 247);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1952254383\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-394555604\">\n\n\t<div id=\"col-830644271\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2421446732\" class=\"text\">\n\t\t\n<p><a href=\"https:\/\/www.starremedies.com\/fr\/madeleine\/#treat\">Traiter les personnes - pas les maladies<\/a>\u00a0|\u00a0<a href=\"https:\/\/www.starremedies.com\/fr\/madeleine\/#body\">R\u00e9cup\u00e9ration du corps et de l'esprit<\/a>\u00a0|\u00a0<a href=\"https:\/\/www.starremedies.com\/fr\/madeleine\/#7bach\">7 Groupes Bach<\/a>\u00a0|\u00a0<a href=\"https:\/\/www.starremedies.com\/fr\/madeleine\/#rescue\">Essence de premiers secours<\/a>\u00a0|\u00a0<a href=\"https:\/\/www.starremedies.com\/fr\/madeleine\/#practice\">De la pratique<\/a><\/p>\n\t\t\n<style>\n#text-2421446732 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n<span class=\"scroll-to\" data-label=\"Scroll to: #treat\" data-bullet=\"true\" data-link=\"#treat\" data-title=\"Treat People - not illness\"><a name=\"treat\"><\/a><\/span>\n<h2>Traiter les personnes et non leur maladie<\/h2>\n<blockquote>\n<p>La maladie n'est pas une punition cruelle, mais simplement une correction ; un instrument que notre propre psych\u00e9 utilise pour mettre en \u00e9vidence nos erreurs, pour nous emp\u00eacher de commettre de plus grandes erreurs et pour nous \u00e9viter de nouveaux dommages - et pour nous ramener sur le chemin de la v\u00e9rit\u00e9 et de la lumi\u00e8re, que nous n'avons jamais eu l'occasion de quitter des yeux.\u00a0<em><strong>Edward Bach<\/strong><\/em><\/p>\n<\/blockquote>\n<p>Le Dr Edward Bach pensait alors que la fa\u00e7on de penser et l'attitude face \u00e0 la vie jouaient un r\u00f4le important dans le d\u00e9veloppement et la gu\u00e9rison des maladies. Pour lui, la maladie \u00e9tait un manque d'harmonie entre le corps et l'esprit. Il supposait que si une personne ne se sentait pas heureuse, une maladie pouvait se d\u00e9velopper apr\u00e8s un certain temps.<\/p>\n<p>Au moyen d'un exemple, je souhaite expliquer clairement comment cela fonctionne dans la pratique :<\/p>\n<p>Imaginez : deux personnes qui n'ont aucun lien de parent\u00e9 vont recevoir un grand choc. La premi\u00e8re est victime d'un accident. Il est terriblement choqu\u00e9, mais ne ressent rien physiquement. Apr\u00e8s quelques semaines, il commence \u00e0 souffrir de maux de t\u00eate et tombe malade. Le second, directeur d'une grande entreprise, doit soudain faire face \u00e0 des crises financi\u00e8res. Lorsqu'il apprend cette nouvelle, il re\u00e7oit un tel choc et, apr\u00e8s quelques jours, une infection nerveuse dans le bras gauche.<\/p>\n<p>Normalement, on donnerait un traitement diff\u00e9rent pour ces deux \u00e9tats, mais quand on regarde l'\u00e9tat psychologique des personnes, il est tr\u00e8s clair que toutes deux ont subi un choc, bien que leurs corps aient r\u00e9agi tr\u00e8s diff\u00e9remment \u00e0 cette situation. Selon la m\u00e9thode d'Edward Bach, vous donnez l'essence qui aide \u00e0 neutraliser le choc.<\/p>\n<p>Edward Bach cherchait dans la nature, entre autres au Pays de Galles, des moyens pour ses m\u00e9thodes de gu\u00e9rison, \u00e0 savoir transformer l'\u00e9tat d'esprit de l'homme d'une attitude n\u00e9gative face \u00e0 la vie ou \u00e0 l'attitude en une attitude positive.<\/p>\n<p>Il l'a trouv\u00e9e sous la forme de fleurs de plantes sauvages, d'arbustes, de buissons et d'arbres. Il en a tir\u00e9 37 essences, la 38e n'\u00e9tant pas fabriqu\u00e9e \u00e0 partir de fleurs, mais \u00e0 partir d'une source \u00e0 laquelle les habitants de la r\u00e9gion attribuent un effet curatif depuis des temps imm\u00e9moriaux.<\/p>\n<div class=\"is-divider divider clearfix\" style=\"margin-top:35px;margin-bottom:35px;\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-377555798\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<span class=\"scroll-to\" data-label=\"Scroll to: #body\" data-bullet=\"true\" data-link=\"#body\" data-title=\"Body &amp; Mind Recovery\"><a name=\"body\"><\/a><\/span>\n<h3>R\u00e9cup\u00e9ration du corps et de l'esprit<\/h3>\n<blockquote>\n<p>Le Dr Bach, hom\u00e9opathe, a d\u00e9couvert dans les ann\u00e9es 1930 que certains types de fleurs apportent de l'harmonie \u00e0 l'esprit humain. Leurs forces positives peuvent d\u00e9bloquer les conditions n\u00e9gatives. Il a suppos\u00e9 que si une personne ne se sent pas heureuse, une maladie peut se d\u00e9velopper apr\u00e8s un certain temps.<\/p>\n<\/blockquote>\n<p>Par exemple, une personne peut \u00eatre accabl\u00e9e par la culpabilit\u00e9 ou trop pr\u00e9occup\u00e9e par le bien-\u00eatre des autres, elle ne peut pas dire \"non\" par crainte de perdre quelque chose. Il existe de nombreux \u00e9tats d'esprit qui font que les gens ne se sentent pas bien. Cela peut entra\u00eener des troubles tels que des affections de la peau, de la t\u00eate et de l'estomac, des inflammations et des douleurs sans cause claire. De v\u00e9ritables maladies peuvent appara\u00eetre par la suite. En recherchant la cause, \u00e0 savoir le manque de bonheur dans la vie, la gu\u00e9rison du corps se produit \u00e9galement ! Le Dr Bach a cr\u00e9\u00e9 38 teintures de fleurs qui agissent chacune sur des \u00e9tats d'esprit sp\u00e9cifiques. Elles peuvent par exemple rem\u00e9dier aux soucis, aux peurs intenses, \u00e0 l'irritation, \u00e0 la tristesse et \u00e0 l'incertitude. La fatigue, le pessimisme et l'impatience peuvent \u00e9galement \u00eatre combattus efficacement.<\/p>\n<p>Les teintures sont prises sous forme de gouttes.<\/p>\n<p>Le cas \u00e9ch\u00e9ant, ils sont \u00e9galement transform\u00e9s en pommade pour traiter de mani\u00e8re \u00e9tonnamment efficace les zones \u00e0 probl\u00e8mes sur et dans le corps. \u00c0 court terme, les personnes se sentent plus \u00e0 l'aise et surtout plus elles-m\u00eames. Les traits de caract\u00e8re n\u00e9gatifs \"cong\u00e9nitaux\" peuvent dispara\u00eetre d\u00e9finitivement gr\u00e2ce \u00e0 la th\u00e9rapie Bloesem et laisser place \u00e0 un sentiment positif, \u00e0 plus de force, de vitalit\u00e9 et de joie de vivre. Il est possible de pr\u00e9venir les maladies de cette mani\u00e8re et c'est pourquoi ce m\u00e9dicament tr\u00e8s simple \u00e0 utiliser peut \u00eatre recommand\u00e9 \u00e0 toute personne qui ne se sent pas de mani\u00e8re optimale sur le plan mental ou \u00e9motionnel.<\/p>\n<p>Les essences de fleurs peuvent \u00eatre appliqu\u00e9es \u00e0 tous les adultes, y compris les enfants pleurnichards, occup\u00e9s, jaloux ou agressifs. De nombreux chiens craintifs ou agressifs sont d\u00e9j\u00e0 devenus des animaux de compagnie agr\u00e9ables gr\u00e2ce \u00e0 ce simple traitement. L'effet d'autres m\u00e9dicaments n'est en rien affect\u00e9.<\/p>\n<p>Le Dr Bach avait \u00e0 l'esprit que cette m\u00e9thode de gu\u00e9rison devait \u00eatre facile \u00e0 appliquer. Avec les essences Blossom dans la maison, on peut facilement att\u00e9nuer beaucoup de probl\u00e8mes dans de nombreuses situations.<\/p>\n<p>La peur des examens, le choc des accidents, les pleurs des b\u00e9b\u00e9s et des enfants, la peur ou le mal du pays sont des outils efficaces. La tristesse et la peur du divorce ou de la mort, la r\u00e9signation et l'abattement du ch\u00f4mage peuvent \u00e9galement \u00eatre modifi\u00e9s. Les adolescents agressifs ou inaccessibles, les beaux-parents rancuniers ou critiques, les membres de la famille trop stress\u00e9s ou \u00e9puis\u00e9s, la paix et l'harmonie peuvent revenir gr\u00e2ce \u00e0 cette m\u00e9thode naturelle.<\/p>\n<p>C'est presque merveilleux, car m\u00eame si apparemment une situation ne change pas d'elle-m\u00eame, on peut faire quelque chose contre tous ces \u00e9tats d'\u00e2me ! Tout simplement parce que l'attitude int\u00e9rieure change avec les pouvoirs de gu\u00e9rison de la floraison. Avec cette m\u00e9thode de gu\u00e9rison unique et innovante, le Dr Bach \u00e9tait r\u00e9solument en avance sur son temps.<\/p>\n<p>Il a ouvert la voie \u00e0 une nouvelle fa\u00e7on de se r\u00e9tablir : la gu\u00e9rison du corps et de l'esprit.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-340335949\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1045499700\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/www.starremedies.com\/wp-content\/uploads\/2016\/02\/edward_bach-3.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.starremedies.com\/wp-content\/uploads\/2016\/02\/edward_bach-3.jpg 250w, https:\/\/www.starremedies.com\/wp-content\/uploads\/2016\/02\/edward_bach-3-80x80.jpg 80w, https:\/\/www.starremedies.com\/wp-content\/uploads\/2016\/02\/edward_bach-3-36x36.jpg 36w, https:\/\/www.starremedies.com\/wp-content\/uploads\/2016\/02\/edward_bach-3-180x180.jpg 180w, https:\/\/www.starremedies.com\/wp-content\/uploads\/2016\/02\/edward_bach-3-120x120.jpg 120w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1045499700 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-717117221\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<span class=\"scroll-to\" data-label=\"Scroll to: #7bach\" data-bullet=\"true\" data-link=\"#7bach\" data-title=\"7 Bach Groups\"><a name=\"7bach\"><\/a><\/span>\n<div class=\"is-divider divider clearfix\" style=\"margin-top:35px;margin-bottom:35px;\"><\/div>\n<h4>7 Groupes Bach<\/h4>\n<p>Edward Bach s'est bas\u00e9 sur ses d\u00e9couvertes et les a divis\u00e9es en 7 groupes, les 7 groupes bach. Ces 7 groupes bach sont directement d\u00e9riv\u00e9s des nosodes bach qu'il a d\u00e9velopp\u00e9s.<\/p>\n<ol>\n<li>La peur<\/li>\n<li>Incertitude<\/li>\n<li>Manque d'int\u00e9r\u00eat pour le pr\u00e9sent<\/li>\n<li>Solitude<\/li>\n<li>Hypersensible aux influences et aux id\u00e9es<\/li>\n<li>D\u00e9couragement et d\u00e9sespoir<\/li>\n<li>Pr\u00e9occupation excessive pour le bien-\u00eatre des autres.<\/li>\n<\/ol>\n<div class=\"is-divider divider clearfix\" style=\"margin-top:35px;margin-bottom:35px;\"><\/div>\n<span class=\"scroll-to\" data-label=\"Scroll to: #rescue\" data-bullet=\"true\" data-link=\"#rescue\" data-title=\"First Aid Essence\"><a name=\"rescue\"><\/a><\/span>\n<h4>Essence de premiers secours ; secours, essence d'urgence, cinq fleurs<\/h4>\n<p>Edward Bach a \u00e9galement d\u00e9velopp\u00e9 une essence de premier secours. Au d\u00e9part, cette essence de premier secours se composait exclusivement de Rock Rose. Plus tard, il a ajout\u00e9 d'autres fleurs de Bach pour lui venir en aide.<\/p>\n<p>L'essence de premier secours est une combinaison de fleurs pr\u00eate \u00e0 l'emploi, qui peut \u00eatre administr\u00e9e comme premier secours dans des situations d'urgence de toutes sortes.<\/p>\n<p>Le m\u00e9lange contient les essences suivantes :<\/p>\n<ul>\n<li>\u00c9toile de Bethl\u00e9em<\/li>\n<li>Rose de roche<\/li>\n<li>Impatiens<\/li>\n<li>Prune \u00e0 cerise<\/li>\n<li>Cl\u00e9matite<\/li>\n<\/ul>\n<p>En cas d'accident grave ou de danger de mort, elle doit \u00eatre administr\u00e9e par tout le monde en guise de premiers soins, tant qu'aucun m\u00e9decin n'est pr\u00e9sent. Toutefois, l'essence de premiers secours ne remplace en aucun cas un m\u00e9decin. NE LAISSEZ PAS L'ESSENCE DE PREMIERS SECOURS DEVENIR UNE HABITUDE. LES ESSENCES DE PREMIERS SECOURS, RESCUE, EMERGENCY ESSENCE, FIVE FLOWER SONT EXCLUSIVEMENT DESTIN\u00c9ES AUX URGENCES \u00c9MOTIONNELLES. LES ESSENCES DE PREMIERS SECOURS NE SERVENT PAS \u00c0 COMPENSER UN MODE DE VIE IMPRUDENT. LES \u00c9LIXIRS FLORAUX BACH ET LA TH\u00c9RAPIE FLORALE BACH NE REMPLACENT PAS UN M\u00c9DECIN OU UN SP\u00c9CIALISTE. IL EST TOUJOURS N\u00c9CESSAIRE DE CONSULTER D'ABORD SON M\u00c9DECIN.<\/p>\n<div class=\"is-divider divider clearfix\" style=\"margin-top:35px;margin-bottom:35px;\"><\/div>\n<span class=\"scroll-to\" data-label=\"Scroll to: #practice\" data-bullet=\"true\" data-link=\"#practice\" data-title=\"From Practice\"><a name=\"practice\"><\/a><\/span>\n<h4>De la pratique<\/h4>\n<p><em><strong>Pour illustrer ce qui pr\u00e9c\u00e8de :<\/strong><\/em><\/p>\n<p>Il y a des ann\u00e9es, un membre du personnel du bach center en Angleterre m'a dit un jour : \"Si j'ai sombr\u00e9 pendant une nuit, j'en prends quelques gouttes le matin et je me remets sur pied\". J'ai \u00e9t\u00e9 tr\u00e8s surpris. Cela ne m'\u00e9tait jamais venu \u00e0 l'esprit. Mais lorsque j'ai commenc\u00e9 \u00e0 y r\u00e9fl\u00e9chir, je me suis dit que cela pouvait aussi \u00eatre le cas. Si vous avez vraiment bu beaucoup d'alcool une fois, je pense qu'il s'agit \u00e9galement d'une sorte de choc. Le terme de choc se r\u00e9f\u00e8re \u00e0 tout ce qui peut perturber l'\u00e9quilibre harmonique de notre syst\u00e8me d'\u00e9nergies.<\/p>\n<p>Vous voyez donc que l'essence de premier secours est utilis\u00e9e comme une sorte d'huile de Haarlemmer, alors qu'en cas de n\u00e9cessit\u00e9, cette essence peut sauver des vies. Je pr\u00e9tends m\u00eame que l'utilisation prolong\u00e9e de l'essence de premier secours peut provoquer des troubles dont on ne conna\u00eet pas l'origine. Par exemple, une personne est venue me chercher de l'essence de premier secours tous les mois pendant une longue p\u00e9riode. Quand je lui ai demand\u00e9 pourquoi elle prenait une bouteille si souvent, elle m'a r\u00e9pondu qu'elle arrivait \u00e0 s'en passer.<\/p>\n<p>Je lui ai conseill\u00e9 de faire quelque chose pour elle-m\u00eame, par exemple de commencer la th\u00e9rapie bach (qu'elle avait suivie pendant 17 ans, chaque semaine, avec un psychiatre), mais elle trouvait cela trop effrayant, elle pr\u00e9f\u00e9rait ne pas laisser les choses auxquelles elle \u00e9tait confront\u00e9e remonter \u00e0 la surface. Je ne voulais plus lui vendre de bouteille et j'ai clairement essay\u00e9 de lui expliquer ce qui pouvait se produire en cas d'utilisation prolong\u00e9e. Je n'aurais peut-\u00eatre pas d\u00fb dire cela, mais je pense qu'il faut donner des informations claires lorsqu'on travaille avec les essences. Malheureusement, je ne l'ai pas revue.<\/p>\n<p><a href=\"https:\/\/blog.madeleinemeuwessen.nl\/fr\/\" target=\"_blank\" rel=\"noopener\">Pour en savoir plus sur les exp\u00e9riences pratiques de Madeleine, consultez son blog.<\/a><\/p>\n<div class=\"is-divider divider clearfix\" style=\"margin-top:35px;margin-bottom:35px;\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1964713656\" class=\"col medium-6 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h4>Supports avec<\/h4>\n<ul>\n<li>Troubles de l'humeur<\/li>\n<li>Probl\u00e8mes li\u00e9s au changement<\/li>\n<li>S'adapter \u00e0 de nouvelles situations<\/li>\n<li>Peur avec cause connue et inconnue<\/li>\n<li>Surcharge \u00e9motionnelle<\/li>\n<li>Image n\u00e9gative de soi<\/li>\n<li>Traumatismes \u00e9motionnels<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1391299917\" class=\"col medium-6 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h4>Traitement et r\u00e9sultats<\/h4>\n<p>S'attaquer aux d\u00e9s\u00e9quilibres \u00e9motionnels qui se sont accumul\u00e9s au fil des ans ne se r\u00e9sout pas en quelques jours. La r\u00e8gle utilis\u00e9e est la suivante : le nombre d'ann\u00e9es pendant lesquelles vous \u00eates g\u00ean\u00e9 par quelque chose correspond au nombre de mois qu'il faut pour que le probl\u00e8me soit r\u00e9solu.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2130079426\" class=\"col medium-6 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h4 id=\"headline-882-3573\" class=\"ct-headline\">Anamn\u00e8se<\/h4>\n<div id=\"_rich_text-887-3573\" class=\"oxy-rich-text c-padding-xs\">\n<p>Il est toujours important de faire un bon diagnostic et d'\u00e9valuer ainsi la cause des probl\u00e8mes \u00e9motionnels. Cela permet de travailler en profondeur avec les \u00e9motions et de r\u00e9soudre les probl\u00e8mes \u00e9motionnels existants.<\/p>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-22367180\" class=\"col medium-6 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h4>Mettre l'accent sur les personnes<\/h4>\n<p>Avec la th\u00e9rapie des fleurs de Bach, c'est l'homme qui est au centre et non le sympt\u00f4me. Les essences de Bach peuvent s'attaquer aux probl\u00e8mes sous-jacents du d\u00e9s\u00e9quilibre. Les essences de fleurs de Bach et la th\u00e9rapie des fleurs de Bach transforment les \u00e9tats d'esprit n\u00e9gatifs en qualit\u00e9s positives.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1952254383 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-3573","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bach flower therapy by Madeleine Meuwessen - Star Remedies<\/title>\n<meta name=\"description\" content=\"Bach flower therapy turns negative states of mind into positive traits. The bach flower therapy by Madeleine Meuwessen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.starremedies.com\/fr\/madeleine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bach flower therapy by Madeleine Meuwessen - Star Remedies\" \/>\n<meta property=\"og:description\" content=\"Bach flower therapy turns negative states of mind into positive traits. The bach flower therapy by Madeleine Meuwessen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.starremedies.com\/fr\/madeleine\/\" \/>\n<meta property=\"og:site_name\" content=\"Star Remedies\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/starremedies\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-05T09:31:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.starremedies.com\\\/madeleine\\\/\",\"url\":\"https:\\\/\\\/www.starremedies.com\\\/madeleine\\\/\",\"name\":\"Bach flower therapy by Madeleine Meuwessen - Star Remedies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.starremedies.com\\\/#website\"},\"datePublished\":\"2016-02-21T10:29:28+00:00\",\"dateModified\":\"2025-02-05T09:31:03+00:00\",\"description\":\"Bach flower therapy turns negative states of mind into positive traits. The bach flower therapy by Madeleine Meuwessen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.starremedies.com\\\/madeleine\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.starremedies.com\\\/madeleine\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.starremedies.com\\\/madeleine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.starremedies.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bach flower therapy by Madeleine Meuwessen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.starremedies.com\\\/#website\",\"url\":\"https:\\\/\\\/www.starremedies.com\\\/\",\"name\":\"Star Remedies\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.starremedies.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.starremedies.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.starremedies.com\\\/#organization\",\"name\":\"Star Remedies\",\"url\":\"https:\\\/\\\/www.starremedies.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.starremedies.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.starremedies.com\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/srl.gif\",\"contentUrl\":\"https:\\\/\\\/www.starremedies.com\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/srl.gif\",\"width\":250,\"height\":250,\"caption\":\"Star Remedies\"},\"image\":{\"@id\":\"https:\\\/\\\/www.starremedies.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/starremedies\\\/\",\"https:\\\/\\\/www.instagram.com\\\/starremedies\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Th\u00e9rapie par les fleurs de Bach par Madeleine Meuwessen - Star Remedies","description":"La th\u00e9rapie par les fleurs de Bach transforme les \u00e9tats d'esprit n\u00e9gatifs en traits positifs. La th\u00e9rapie des fleurs de Bach par Madeleine Meuwessen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.starremedies.com\/fr\/madeleine\/","og_locale":"fr_FR","og_type":"article","og_title":"Bach flower therapy by Madeleine Meuwessen - Star Remedies","og_description":"Bach flower therapy turns negative states of mind into positive traits. The bach flower therapy by Madeleine Meuwessen.","og_url":"https:\/\/www.starremedies.com\/fr\/madeleine\/","og_site_name":"Star Remedies","article_publisher":"https:\/\/www.facebook.com\/starremedies\/","article_modified_time":"2025-02-05T09:31:03+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.starremedies.com\/madeleine\/","url":"https:\/\/www.starremedies.com\/madeleine\/","name":"Th\u00e9rapie par les fleurs de Bach par Madeleine Meuwessen - Star Remedies","isPartOf":{"@id":"https:\/\/www.starremedies.com\/#website"},"datePublished":"2016-02-21T10:29:28+00:00","dateModified":"2025-02-05T09:31:03+00:00","description":"La th\u00e9rapie par les fleurs de Bach transforme les \u00e9tats d'esprit n\u00e9gatifs en traits positifs. La th\u00e9rapie des fleurs de Bach par Madeleine Meuwessen.","breadcrumb":{"@id":"https:\/\/www.starremedies.com\/madeleine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.starremedies.com\/madeleine\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.starremedies.com\/madeleine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.starremedies.com\/"},{"@type":"ListItem","position":2,"name":"Bach flower therapy by Madeleine Meuwessen"}]},{"@type":"WebSite","@id":"https:\/\/www.starremedies.com\/#website","url":"https:\/\/www.starremedies.com\/","name":"Rem\u00e8des d'\u00e9toiles","description":"","publisher":{"@id":"https:\/\/www.starremedies.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.starremedies.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.starremedies.com\/#organization","name":"Rem\u00e8des d'\u00e9toiles","url":"https:\/\/www.starremedies.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.starremedies.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.starremedies.com\/wp-content\/uploads\/2016\/02\/srl.gif","contentUrl":"https:\/\/www.starremedies.com\/wp-content\/uploads\/2016\/02\/srl.gif","width":250,"height":250,"caption":"Star Remedies"},"image":{"@id":"https:\/\/www.starremedies.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/starremedies\/","https:\/\/www.instagram.com\/starremedies\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.starremedies.com\/fr\/wp-json\/wp\/v2\/pages\/3573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.starremedies.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.starremedies.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.starremedies.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.starremedies.com\/fr\/wp-json\/wp\/v2\/comments?post=3573"}],"version-history":[{"count":10,"href":"https:\/\/www.starremedies.com\/fr\/wp-json\/wp\/v2\/pages\/3573\/revisions"}],"predecessor-version":[{"id":27965,"href":"https:\/\/www.starremedies.com\/fr\/wp-json\/wp\/v2\/pages\/3573\/revisions\/27965"}],"wp:attachment":[{"href":"https:\/\/www.starremedies.com\/fr\/wp-json\/wp\/v2\/media?parent=3573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}